{"id":17233,"date":"2023-06-26T22:45:23","date_gmt":"2023-06-27T01:45:23","guid":{"rendered":"https:\/\/noticiasnoface.com.br\/?p=17233"},"modified":"2023-06-27T08:06:45","modified_gmt":"2023-06-27T11:06:45","slug":"camara-de-natal-aprova-ldo-2024-com-emendas-em-segunda-discussao-2","status":"publish","type":"post","link":"https:\/\/noticiasnoface.com.br\/index.php\/2023\/06\/26\/camara-de-natal-aprova-ldo-2024-com-emendas-em-segunda-discussao-2\/","title":{"rendered":"C\u00e2mara de Natal aprova LDO 2024, com emendas, em segunda discuss\u00e3o"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img data-opt-id=506200585  fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"660\" src=\"https:\/\/mlbfrsat7ahr.i.optimole.com\/w:1024\/h:660\/q:mauto\/ig:avif\/https:\/\/noticiasnoface.com.br\/wp-content\/uploads\/2023\/06\/photo-output-72.jpg\" alt=\"\" class=\"wp-image-17244\" srcset=\"https:\/\/mlbfrsat7ahr.i.optimole.com\/w:1024\/h:660\/q:mauto\/ig:avif\/https:\/\/noticiasnoface.com.br\/wp-content\/uploads\/2023\/06\/photo-output-72.jpg 1024w, https:\/\/mlbfrsat7ahr.i.optimole.com\/w:300\/h:193\/q:mauto\/ig:avif\/https:\/\/noticiasnoface.com.br\/wp-content\/uploads\/2023\/06\/photo-output-72.jpg 300w, https:\/\/mlbfrsat7ahr.i.optimole.com\/w:768\/h:495\/q:mauto\/ig:avif\/https:\/\/noticiasnoface.com.br\/wp-content\/uploads\/2023\/06\/photo-output-72.jpg 768w, https:\/\/mlbfrsat7ahr.i.optimole.com\/w:1536\/h:989\/q:mauto\/ig:avif\/https:\/\/noticiasnoface.com.br\/wp-content\/uploads\/2023\/06\/photo-output-72.jpg 1536w, https:\/\/mlbfrsat7ahr.i.optimole.com\/w:1676\/h:1080\/q:mauto\/ig:avif\/https:\/\/noticiasnoface.com.br\/wp-content\/uploads\/2023\/06\/photo-output-72.jpg 2048w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">A C\u00e2mara Municipal de Natal aprovou em segunda discuss\u00e3o, na sess\u00e3o ordin\u00e1ria desta quinta-feira (22), o Projeto de Lei n\u00b0 284\/2023 encaminhado pelo Executivo que trata da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO 2024). Amplamente discutida pelos parlamentares, a mat\u00e9ria teve 249 emendas apresentadas por todas as bancadas e 111 emendas aprovadas. A pe\u00e7a or\u00e7ament\u00e1ria estabelece quais ser\u00e3o as metas e prioridades para o ano seguinte. Para isso, fixa o montante de recursos que o governo pretende economizar; tra\u00e7a regras, veda\u00e7\u00f5es e limites para as despesas dos Poderes.<br \/>Neste terceiro dia de vota\u00e7\u00e3o, o debate aconteceu em torno de tr\u00eas emendas n\u00e3o consensuais de autoria do vereador Daniel Valen\u00e7a (PT) que, por fim, foram derrubadas pela maioria dos parlamentares presentes no plen\u00e1rio. Por\u00e9m, ainda poder\u00e3o ser discutidas e alinhadas no Plano Plurianual, que ser\u00e1 revisado no segundo semestre.<br \/>&#8220;Apresentamos propostas para garantir piso salarial para professores, enfermeiros, t\u00e9cnicos e auxiliares de enfermagem, al\u00e9m de agentes de sa\u00fade, haja vista que existe previs\u00e3o constitucional para isso. Tamb\u00e9m tentamos proibir a transfer\u00eancia de recursos para comunidades terap\u00eauticas, pois a lei da reforma psiqui\u00e1trica determina que a Pol\u00edtica de Sa\u00fade Mental n\u00e3o pode financiar uma perspectiva asilar. Mas, infelizmente, n\u00e3o conseguimos consenso com a maioria&#8221;, explicou Daniel Valen\u00e7a.<br \/>O vice-l\u00edder da bancada governista, vereador Raniere Barbosa (Avante), avaliou a aprecia\u00e7\u00e3o da LDO 2024. &#8220;Os debates aconteceram de forma democr\u00e1tica, tranquila e produtiva. Todas as bancadas tiveram a oportunidade de oferecer suas contribui\u00e7\u00f5es atrav\u00e9s de emendas importantes para a popula\u00e7\u00e3o. Portanto, mais uma vez o Legislativo natalense cumpriu o seu papel de votar leis que garantem o desenvolvimento da nossa cidade&#8221;.<br \/>Na sequ\u00eancia, foi derrubado um veto integral a Emenda n\u00b0 50 ao Projeto de Lei Complementar n.\u00ba 004\/2022, de autoria do Executivo, que regulamenta o uso e a ocupa\u00e7\u00e3o do solo, delimita as subzonas e estabelece as prescri\u00e7\u00f5es urban\u00edsticas para a Zona de Prote\u00e7\u00e3o Ambiental 9 (ZPA 9), abrangendo parte dos bairros de Lagoa Azul, Paju\u00e7ara e Redinha, Regi\u00e3o Administrativa Norte do Munic\u00edpio. &#8220;Quero agradecer a todos os colegas por manterem esse texto que visa, unicamente, garantir crescimento com qualidade de vida para as comunidades que vivem na regi\u00e3o&#8221;, pontuou o vereador Eribaldo Medeiros (PSB), autor da emenda.<br \/>Ao final da sess\u00e3o, os parlamentares deram parecer favor\u00e1vel a tr\u00eas projetos de lei em segunda discuss\u00e3o: PL 430\/2022, do vereador Aroldo Alves (PSDB), que institui no Calend\u00e1rio de Eventos da cidade o Dia Florescer da Autoestima da Mulher, PL 161\/2023, do vereador Anderson Lopes (SD), que reconhece de Utilidade P\u00fablica da Federa\u00e7\u00e3o de Esportes Eletr\u00f4nicos do Rio Grande do Norte, PL 259\/2023, do vereador presidente da Casa Eriko J\u00e1come (MDB), que reconhece de Utilidade P\u00fablica a Associa\u00e7\u00e3o Natal Agora, e o PL 212\/2023, da vereadora Nina Souza (PDT), que institui o Dia Municipal da mulher na Engenharia, a ser celebrado em 23 de junho.<br \/><strong><em>Texto: Junior Martins<br \/>Fotos: Ver\u00f4nica Macedo<\/em><\/strong><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[517],"tags":[],"class_list":["post-17233","post","type-post","status-publish","format-standard","hentry","category-aconteceu"],"_links":{"self":[{"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17233"}],"version-history":[{"count":3,"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17233\/revisions"}],"predecessor-version":[{"id":17246,"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17233\/revisions\/17246"}],"wp:attachment":[{"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasnoface.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}